{"id":4199,"date":"2020-03-13T12:11:34","date_gmt":"2020-03-13T10:11:34","guid":{"rendered":"https:\/\/www.makelaalu.fi\/?p=4199"},"modified":"2020-03-13T14:42:10","modified_gmt":"2020-03-13T12:42:10","slug":"mitteilung-ueber-das-covid-19","status":"publish","type":"post","link":"https:\/\/makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/","title":{"rendered":"Mitteilung \u00fcber das COVID-19"},"content":{"rendered":"\n<h3><strong>Sehr geehrter Kunde und Gesch\u00e4ftspartner,<\/strong><\/h3>\n<p>Als Teil unseres Notfallplans haben wir bei M\u00e4kel\u00e4 Alu Oy einen Leitfaden sowie Vorgehensweisen bez\u00fcglich des Coronavirus (\u201dCOVID-19\u201d) eingef\u00fchrt, um die Sicherheit unserer Mitarbeiter, Kunden sowie Gesch\u00e4ftspartner zu sichern, die weitere Ausbreitung des Virus zu verhindern sowie die Auswirkungen einer m\u00f6glichen Ansteckung und Exposition einzugrenzen.<\/p>\n<p>Der Leitfaden beinhaltet Informationen zu \u00dcbertragungswegen des Coronavirus, Verhinderung einer Infektion, Ma\u00dfnahmen bei einer Exposition und einer Erkrankung oder einem Verdacht auf Erkrankung zuhause und am Arbeitsplatz, Abwehrma\u00dfnahmen am Arbeitsplatz einschlie\u00dflich Meldepraktiken, Reisevorschriften sowie Anweisungen zur Bewegung der Mitarbeiter am Arbeitsplatz und Nutzung von allgemeinen R\u00e4umlichkeiten (z.B. Umkleide- sowie Gemeinschaftsr\u00e4ume).<\/p>\n<p>Mithilfe dieser Ma\u00dfnahmen sichern wir die pers\u00f6nliche Sicherheit unserer Mitarbeiter, unserer Kunden und unserer Gesch\u00e4ftspartner und gleichzeitig eine m\u00f6glichst st\u00f6rungsfreie Gesch\u00e4ftst\u00e4tigkeit bei unseren Kunden und bei uns selbst. Zum jetzigen Zeitpunkt hat die Epidemie keinerlei Auswirkungen auf Kundenlieferungen.<\/p>\n<p><a href=\"https:\/\/www.makelaalu.fi\/de\/unkategorisiert\/anweisung-fuer-besucher-bezueglich-des-coronavirus\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hier befindet<\/a> sich auf unserer Webseite eine Anweisung f\u00fcr Kunden und Gesch\u00e4ftspartner, die uns besuchen. Wir bitten darum, diese Anweisung zu befolgen, damit wir f\u00fcr die Sicherheit unserer Mitarbeiter garantieren k\u00f6nnen.<\/p>\n<p>Sollte sich an der Situation grundlegend etwas \u00e4ndern, werden wir \u00fcber m\u00f6gliche Auswirkungen unverz\u00fcglich berichten.<\/p>\n<p>Mit freundlichen Gr\u00fc\u00dfen,<br \/>M\u00e4kel\u00e4 Alu Oy<br \/><em>Petri M\u00e4kel\u00e4<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"Sehr geehrter Kunde und Gesch\u00e4ftspartner, Als Teil unseres Notfallplans haben wir bei M\u00e4kel\u00e4 Alu Oy einen Leitfaden sowie Vorgehensweisen bez\u00fcglich des Coronavirus (\u201dCOVID-19\u201d) eingef\u00fchrt, um die Sicherheit unserer Mitarbeiter, Kunden sowie Gesch\u00e4ftspartner zu sichern, die weitere Ausbreitung des Virus zu verhindern sowie die Auswirkungen einer m\u00f6glichen Ansteckung und Exposition einzugrenzen. Der Leitfaden beinhaltet Informationen zu \u00dcbertragungswegen des Coronavirus, Verhinderung einer Infektion, Ma\u00dfnahmen bei einer Exposition und einer Erkrankung oder einem Verdacht auf Erkrankung zuhause und am Arbeitsplatz, Abwehrma\u00dfnahmen am Arbeitsplatz einschlie\u00dflich Meldepraktiken, Reisevorschriften sowie Anweisungen zur Bewegung der Mitarbeiter am Arbeitsplatz und Nutzung von allgemeinen R\u00e4umlichkeiten (z.B. Umkleide- sowie Gemeinschaftsr\u00e4ume). Mithilfe dieser Ma\u00dfnahmen sichern wir die pers\u00f6nliche Sicherheit unserer Mitarbeiter, unserer Kunden und unserer Gesch\u00e4ftspartner und gleichzeitig eine m\u00f6glichst st\u00f6rungsfreie Gesch\u00e4ftst\u00e4tigkeit bei unseren Kunden und bei uns selbst. Zum jetzigen Zeitpunkt hat die Epidemie keinerlei Auswirkungen auf Kundenlieferungen. Hier befindet sich auf unserer Webseite eine Anweisung f\u00fcr Kunden und Gesch\u00e4ftspartner, die uns besuchen. Wir bitten darum, diese Anweisung zu befolgen, damit wir f\u00fcr die Sicherheit unserer Mitarbeiter garantieren k\u00f6nnen. Sollte sich an der Situation grundlegend etwas \u00e4ndern, werden wir \u00fcber m\u00f6gliche Auswirkungen unverz\u00fcglich berichten. Mit freundlichen Gr\u00fc\u00dfen,M\u00e4kel\u00e4 Alu OyPetri M\u00e4kel\u00e4","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-4199","post","type-post","status-publish","format-standard","hentry","category-aktuelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mitteilung \u00fcber das COVID-19 - M&auml;kel&auml; Alu Oy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mitteilung \u00fcber das COVID-19 - M&auml;kel&auml; Alu Oy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"M&auml;kel&auml; Alu Oy\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-13T10:11:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-13T12:42:10+00:00\" \/>\n<meta name=\"author\" content=\"Susanna Korkiatupa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susanna Korkiatupa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/de\\\/aktuelles\\\/mitteilung-ueber-das-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/de\\\/aktuelles\\\/mitteilung-ueber-das-covid-19\\\/\"},\"author\":{\"name\":\"Susanna Korkiatupa\",\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#\\\/schema\\\/person\\\/9a809b6cc4e323d49d85ca0a349b40af\"},\"headline\":\"Mitteilung \u00fcber das COVID-19\",\"datePublished\":\"2020-03-13T10:11:34+00:00\",\"dateModified\":\"2020-03-13T12:42:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/de\\\/aktuelles\\\/mitteilung-ueber-das-covid-19\\\/\"},\"wordCount\":224,\"articleSection\":[\"Aktuelles\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/de\\\/aktuelles\\\/mitteilung-ueber-das-covid-19\\\/\",\"url\":\"https:\\\/\\\/dev.makelaalu.fi\\\/de\\\/aktuelles\\\/mitteilung-ueber-das-covid-19\\\/\",\"name\":\"Mitteilung \u00fcber das COVID-19 - M&auml;kel&auml; Alu Oy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#website\"},\"datePublished\":\"2020-03-13T10:11:34+00:00\",\"dateModified\":\"2020-03-13T12:42:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#\\\/schema\\\/person\\\/9a809b6cc4e323d49d85ca0a349b40af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/de\\\/aktuelles\\\/mitteilung-ueber-das-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev.makelaalu.fi\\\/de\\\/aktuelles\\\/mitteilung-ueber-das-covid-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/de\\\/aktuelles\\\/mitteilung-ueber-das-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Frontpage\",\"item\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitteilung \u00fcber das COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#website\",\"url\":\"https:\\\/\\\/dev.makelaalu.fi\\\/\",\"name\":\"M&auml;kel&auml; Alu Oy\",\"description\":\"Alumiiniprofiilien puristaminen vuosikymmenten kokemuksella.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev.makelaalu.fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#\\\/schema\\\/person\\\/9a809b6cc4e323d49d85ca0a349b40af\",\"name\":\"Susanna Korkiatupa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g\",\"caption\":\"Susanna Korkiatupa\"},\"url\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/author\\\/susannak\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mitteilung \u00fcber das COVID-19 - M&auml;kel&auml; Alu Oy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/","og_locale":"de_DE","og_type":"article","og_title":"Mitteilung \u00fcber das COVID-19 - M&auml;kel&auml; Alu Oy","og_url":"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/","og_site_name":"M&auml;kel&auml; Alu Oy","article_published_time":"2020-03-13T10:11:34+00:00","article_modified_time":"2020-03-13T12:42:10+00:00","author":"Susanna Korkiatupa","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Susanna Korkiatupa","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/#article","isPartOf":{"@id":"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/"},"author":{"name":"Susanna Korkiatupa","@id":"https:\/\/dev.makelaalu.fi\/#\/schema\/person\/9a809b6cc4e323d49d85ca0a349b40af"},"headline":"Mitteilung \u00fcber das COVID-19","datePublished":"2020-03-13T10:11:34+00:00","dateModified":"2020-03-13T12:42:10+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/"},"wordCount":224,"articleSection":["Aktuelles"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/","url":"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/","name":"Mitteilung \u00fcber das COVID-19 - M&auml;kel&auml; Alu Oy","isPartOf":{"@id":"https:\/\/dev.makelaalu.fi\/#website"},"datePublished":"2020-03-13T10:11:34+00:00","dateModified":"2020-03-13T12:42:10+00:00","author":{"@id":"https:\/\/dev.makelaalu.fi\/#\/schema\/person\/9a809b6cc4e323d49d85ca0a349b40af"},"breadcrumb":{"@id":"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.makelaalu.fi\/de\/aktuelles\/mitteilung-ueber-das-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Frontpage","item":"https:\/\/makelaalu.fi\/de\/"},{"@type":"ListItem","position":2,"name":"Mitteilung \u00fcber das COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/dev.makelaalu.fi\/#website","url":"https:\/\/dev.makelaalu.fi\/","name":"M&auml;kel&auml; Alu Oy","description":"Alumiiniprofiilien puristaminen vuosikymmenten kokemuksella.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.makelaalu.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/dev.makelaalu.fi\/#\/schema\/person\/9a809b6cc4e323d49d85ca0a349b40af","name":"Susanna Korkiatupa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g","caption":"Susanna Korkiatupa"},"url":"https:\/\/makelaalu.fi\/de\/author\/susannak\/"}]}},"_links":{"self":[{"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/posts\/4199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/comments?post=4199"}],"version-history":[{"count":2,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/posts\/4199\/revisions"}],"predecessor-version":[{"id":4214,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/posts\/4199\/revisions\/4214"}],"wp:attachment":[{"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/media?parent=4199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/categories?post=4199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/tags?post=4199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}