{"id":9274,"date":"2023-01-11T09:43:47","date_gmt":"2023-01-11T07:43:47","guid":{"rendered":"https:\/\/makelaalu.fi\/?p=9274"},"modified":"2023-01-11T12:11:51","modified_gmt":"2023-01-11T10:11:51","slug":"unser-neuer-geschaftsfuhrer-marko-orpana","status":"publish","type":"post","link":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/","title":{"rendered":"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana"},"content":{"rendered":"<p>Unser neuer Gesch\u00e4ftsf\u00fchrer hei\u00dft <strong>Marko Orpana<\/strong>. Der bisherige Gesch\u00e4ftsf\u00fchrer <strong>Petri M\u00e4kel\u00e4<\/strong> bleibt weiterhin als Vorstandsvorsitzender in unserem Unternehmen t\u00e4tig.<\/p>\n<p>Herr Orpana arbeitet derzeit noch als Gesch\u00e4ftsf\u00fchrer des Softwareherstellers Rauhala Yhti\u00f6t Oy. Er verf\u00fcgt \u00fcber langj\u00e4hrige Erfahrung in der Leitung vom Servicegesch\u00e4ft.<\/p>\n<p>\u201eIch glaube, dass Marko uns in dieser Hinsicht viel zu bieten hat, aber vor allem glaube ich, dass er uns als kompetente F\u00fchrungskraft inspirieren wird. Ich freue mich sehr auf die Zusammenarbeit mit Marko\u201c, sagt Petri M\u00e4kel\u00e4.<\/p>\n<p>Marko Orpana startet am 1.3. in der Gesch\u00e4ftsf\u00fchrung von M\u00e4kel\u00e4 Alu.<\/p>\n<p>\u201eIch komme zu M\u00e4kel\u00e4 Alu mit gro\u00dfer Freude, aber auch mit Demut. M\u00e4kel\u00e4 Alu ist ein gro\u00dfer Player in der Branche, aber ich mag insbesondere die Unternehmenswerte und -strategie. Vor allem mit Petri haben wir sehr \u00e4hnliche Vorstellungen dar\u00fcber, wie die Dinge laufen sollen\u201c, sagt er.<\/p>\n<p>&nbsp;<\/p>\n<h2>Langj\u00e4hrige Managementerfahrung<\/h2>\n<p>In Kauhajoki geboren, lebt Marko Orpana mit seiner Familie nun in Sein\u00e4joki. Er hat einen Master-Abschluss in Wirtschaftswissenschaften. W\u00e4hrend seiner Zeit in S\u00fcdfinnland arbeitete er unter anderem f\u00fcr die Telekomkonzerne Elisa und Itella. Nachdem er nach S\u00fcd\u00f6sterbotten zur\u00fcckgekehrt war, arbeitete er lange Zeit f\u00fcr den Medienkonzern Ilkka-Yhtym\u00e4.<\/p>\n<p>\u201eMeine Aufgabe als F\u00fchrungskraft sehe ich so: ich bin im Kundenservice t\u00e4tig, und meine Kunden sind die Mitarbeiter des Unternehmens. Den Mitarbeitern ihre Arbeit in positiver Atmosph\u00e4re zu erm\u00f6glichen ist mir wichtig\u201c, sagt Orpana.<\/p>\n<p>\u201eIch gehe mit dem Gedanken an diese Aufgabe heran, dass ich in erster Linie lernen, zuh\u00f6ren und mit den Mitarbeitern austauschen werde. Ich freue mich schon darauf!\u201c, f\u00e4hrt er fort.<\/p>\n<p>Orpana wagt den Sprung in eine v\u00f6llig neue Branche. Das ist eine bewusste strategische Entscheidung von M\u00e4kel\u00e4 Alu.<\/p>\n<p>\u201eWir haben ein hochqualifiziertes Managementteam, das sich unserer Strategie verschrieben hat, und es ist gro\u00dfartig, dass wir unser Gesch\u00e4ft gemeinsam mit ihnen vorantreiben k\u00f6nnen. Deshalb haben wir nicht nach speziellen Fachkenntnissen in einem bestimmten Bereich gesucht, sondern nach einer guten F\u00fchrungspers\u00f6nlichkeit, und ich glaube, dass Marko genau das ist. Die Tatsache, dass Marko einen starken Hintergrund im Servicegesch\u00e4ft hat, ist eine gro\u00dfe Chance f\u00fcr uns, unsere eigenen Dienstleistungen voranzubringen. Auch aufgrund seiner Werte passt er gut in unseren Betrieb, was absolut wichtig f\u00fcr eine gute Zusammenarbeit ist.\u201c, sagt Petri M\u00e4kel\u00e4.<\/p>\n<p>&nbsp;<\/p>\n<h2>Nachhaltigkeit und Service als Wettbewerbsvorteil<\/h2>\n<p>Marko Orpana sieht das Gesch\u00e4ftsmodell von M\u00e4kel\u00e4 Alu, dem es gelungen ist, den Schwerpunkt vom selbst produzierten Produkt in ein Dienstleistungsgesch\u00e4ft umzuwandeln, als Differenzierungsfaktor und strategischen Wettbewerbsvorteil. Viele Aluminiumpresswerke produzieren nur Produkte.<\/p>\n<p>\u201eM\u00e4kel\u00e4 Alu erkennt, was der Kunde wirklich braucht, manchmal sogar besser als der Kunde selbst. Das ist es, worum es bei unserer Arbeit im Grunde geht. M\u00e4kel\u00e4 Alu m\u00f6chte wirklich Teil der Wertsch\u00f6pfungskette des Kunden sein und ihm helfen, sein eigenes Gesch\u00e4ft zu entwickeln\u201c, sagt er.<\/p>\n<p>M\u00e4kel\u00e4 Alu bietet seinen Kunden zum Beispiel einen Lagerservice und die Oberfl\u00e4chenbehandlung von Aluminiumprofilen, und diese Dienste k\u00f6nnen in die Kundenproduktion integriert werden.<\/p>\n<p>\u201eM\u00e4kel\u00e4 Alu ist ein Unternehmen, das sich nachhaltig weiterentwickeln will. Ob Wohlbefinden am Arbeitsplatz, Arbeitssicherheit oder Klimafragen: Nachhaltigkeit ist die treibende Kraft. Das Unternehmen \u00fcbernimmt Verantwortung f\u00fcr seine T\u00e4tigkeit und den Planeten, so gut es kann\u201c, sagt Marko Orpana.<\/p>\n<p>Mehr \u00fcber unsere Nachhaltigkeitsaktivit\u00e4ten unter \u201e<a href=\"https:\/\/makelaalu.fi\/de\/verantwortung\/\">Nachhaltigkeit<\/a>\u201c.<\/p>\n","protected":false},"excerpt":{"rendered":"Unser neuer Gesch\u00e4ftsf\u00fchrer hei\u00dft Marko Orpana. Der bisherige Gesch\u00e4ftsf\u00fchrer Petri M\u00e4kel\u00e4 bleibt weiterhin als Vorstandsvorsitzender in unserem Unternehmen t\u00e4tig. Herr Orpana arbeitet derzeit noch als Gesch\u00e4ftsf\u00fchrer des Softwareherstellers Rauhala Yhti\u00f6t Oy. Er verf\u00fcgt \u00fcber langj\u00e4hrige Erfahrung in der Leitung vom Servicegesch\u00e4ft. \u201eIch glaube, dass Marko uns in dieser Hinsicht viel zu bieten hat, aber vor allem glaube ich, dass er uns als kompetente F\u00fchrungskraft inspirieren wird. Ich freue mich sehr auf die Zusammenarbeit mit Marko\u201c, sagt Petri M\u00e4kel\u00e4. Marko Orpana startet am 1.3. in der Gesch\u00e4ftsf\u00fchrung von M\u00e4kel\u00e4 Alu. \u201eIch komme zu M\u00e4kel\u00e4 Alu mit gro\u00dfer Freude, aber auch mit Demut. M\u00e4kel\u00e4 Alu ist ein gro\u00dfer Player in der Branche, aber ich mag insbesondere die Unternehmenswerte und -strategie. Vor allem mit Petri haben wir sehr \u00e4hnliche Vorstellungen dar\u00fcber, wie die Dinge laufen sollen\u201c, sagt er. &nbsp; Langj\u00e4hrige Managementerfahrung In Kauhajoki geboren, lebt Marko Orpana mit seiner Familie nun in Sein\u00e4joki. Er hat einen Master-Abschluss in Wirtschaftswissenschaften. W\u00e4hrend seiner Zeit in S\u00fcdfinnland arbeitete er unter anderem f\u00fcr die Telekomkonzerne Elisa und Itella. Nachdem er nach S\u00fcd\u00f6sterbotten zur\u00fcckgekehrt war, arbeitete er lange Zeit f\u00fcr den Medienkonzern Ilkka-Yhtym\u00e4. \u201eMeine Aufgabe als F\u00fchrungskraft sehe ich so: ich bin im Kundenservice t\u00e4tig, und meine Kunden sind die Mitarbeiter des Unternehmens. Den Mitarbeitern ihre Arbeit in positiver Atmosph\u00e4re zu erm\u00f6glichen ist mir wichtig\u201c, sagt Orpana. \u201eIch gehe mit dem Gedanken an diese Aufgabe heran, dass ich in erster Linie lernen, zuh\u00f6ren und mit den Mitarbeitern austauschen werde. Ich freue mich schon darauf!\u201c, f\u00e4hrt er fort. Orpana wagt den Sprung in eine v\u00f6llig neue Branche. Das ist eine bewusste strategische Entscheidung von M\u00e4kel\u00e4 Alu. \u201eWir haben ein hochqualifiziertes Managementteam, das sich unserer Strategie verschrieben hat, und es ist gro\u00dfartig, dass wir unser Gesch\u00e4ft gemeinsam mit ihnen vorantreiben k\u00f6nnen. Deshalb haben wir nicht nach speziellen Fachkenntnissen in einem bestimmten Bereich gesucht, sondern nach einer guten F\u00fchrungspers\u00f6nlichkeit, und ich glaube, dass Marko genau das ist. Die Tatsache, dass Marko einen starken Hintergrund im Servicegesch\u00e4ft hat, ist eine gro\u00dfe Chance f\u00fcr uns, unsere eigenen Dienstleistungen voranzubringen. Auch aufgrund seiner Werte passt er gut in unseren Betrieb, was absolut wichtig f\u00fcr eine gute Zusammenarbeit ist.\u201c, sagt Petri M\u00e4kel\u00e4. &nbsp; Nachhaltigkeit und Service als Wettbewerbsvorteil Marko Orpana sieht das Gesch\u00e4ftsmodell von M\u00e4kel\u00e4 Alu, dem es gelungen ist, den Schwerpunkt vom selbst produzierten Produkt in ein Dienstleistungsgesch\u00e4ft umzuwandeln, als Differenzierungsfaktor und strategischen Wettbewerbsvorteil. Viele Aluminiumpresswerke produzieren nur Produkte. \u201eM\u00e4kel\u00e4 Alu erkennt, was der Kunde wirklich braucht, manchmal sogar besser als der Kunde selbst. Das ist es, worum es bei unserer Arbeit im Grunde geht. M\u00e4kel\u00e4 Alu m\u00f6chte wirklich Teil der Wertsch\u00f6pfungskette des Kunden sein und ihm helfen, sein eigenes Gesch\u00e4ft zu entwickeln\u201c, sagt er. M\u00e4kel\u00e4 Alu bietet seinen Kunden zum Beispiel einen Lagerservice und die Oberfl\u00e4chenbehandlung von Aluminiumprofilen, und diese Dienste k\u00f6nnen in die Kundenproduktion integriert werden. \u201eM\u00e4kel\u00e4 Alu ist ein Unternehmen, das sich nachhaltig weiterentwickeln will. Ob Wohlbefinden am Arbeitsplatz, Arbeitssicherheit oder Klimafragen: Nachhaltigkeit ist die treibende Kraft. Das Unternehmen \u00fcbernimmt Verantwortung f\u00fcr seine T\u00e4tigkeit und den Planeten, so gut es kann\u201c, sagt Marko Orpana. Mehr \u00fcber unsere Nachhaltigkeitsaktivit\u00e4ten unter \u201eNachhaltigkeit\u201c.","protected":false},"author":2,"featured_media":9260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-9274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana - M&auml;kel&auml; Alu Oy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana - M&auml;kel&auml; Alu Oy\" \/>\n<meta property=\"og:description\" content=\"Unser neuer Gesch\u00e4ftsf\u00fchrer hei\u00dft Marko Orpana. Der bisherige Gesch\u00e4ftsf\u00fchrer Petri M\u00e4kel\u00e4 bleibt weiterhin als Vorstandsvorsitzender in unserem Unternehmen t\u00e4tig. Herr Orpana arbeitet derzeit noch als Gesch\u00e4ftsf\u00fchrer des Softwareherstellers Rauhala Yhti\u00f6t Oy. Er verf\u00fcgt \u00fcber langj\u00e4hrige Erfahrung in der Leitung vom Servicegesch\u00e4ft. \u201eIch glaube, dass Marko uns in dieser Hinsicht viel zu bieten hat, aber vor allem glaube ich, dass er uns als kompetente F\u00fchrungskraft inspirieren wird. Ich freue mich sehr auf die Zusammenarbeit mit Marko\u201c, sagt Petri M\u00e4kel\u00e4. Marko Orpana startet am 1.3. in der Gesch\u00e4ftsf\u00fchrung von M\u00e4kel\u00e4 Alu. \u201eIch komme zu M\u00e4kel\u00e4 Alu mit gro\u00dfer Freude, aber auch mit Demut. M\u00e4kel\u00e4 Alu ist ein gro\u00dfer Player in der Branche, aber ich mag insbesondere die Unternehmenswerte und -strategie. Vor allem mit Petri haben wir sehr \u00e4hnliche Vorstellungen dar\u00fcber, wie die Dinge laufen sollen\u201c, sagt er. &nbsp; Langj\u00e4hrige Managementerfahrung In Kauhajoki geboren, lebt Marko Orpana mit seiner Familie nun in Sein\u00e4joki. Er hat einen Master-Abschluss in Wirtschaftswissenschaften. W\u00e4hrend seiner Zeit in S\u00fcdfinnland arbeitete er unter anderem f\u00fcr die Telekomkonzerne Elisa und Itella. Nachdem er nach S\u00fcd\u00f6sterbotten zur\u00fcckgekehrt war, arbeitete er lange Zeit f\u00fcr den Medienkonzern Ilkka-Yhtym\u00e4. \u201eMeine Aufgabe als F\u00fchrungskraft sehe ich so: ich bin im Kundenservice t\u00e4tig, und meine Kunden sind die Mitarbeiter des Unternehmens. Den Mitarbeitern ihre Arbeit in positiver Atmosph\u00e4re zu erm\u00f6glichen ist mir wichtig\u201c, sagt Orpana. \u201eIch gehe mit dem Gedanken an diese Aufgabe heran, dass ich in erster Linie lernen, zuh\u00f6ren und mit den Mitarbeitern austauschen werde. Ich freue mich schon darauf!\u201c, f\u00e4hrt er fort. Orpana wagt den Sprung in eine v\u00f6llig neue Branche. Das ist eine bewusste strategische Entscheidung von M\u00e4kel\u00e4 Alu. \u201eWir haben ein hochqualifiziertes Managementteam, das sich unserer Strategie verschrieben hat, und es ist gro\u00dfartig, dass wir unser Gesch\u00e4ft gemeinsam mit ihnen vorantreiben k\u00f6nnen. Deshalb haben wir nicht nach speziellen Fachkenntnissen in einem bestimmten Bereich gesucht, sondern nach einer guten F\u00fchrungspers\u00f6nlichkeit, und ich glaube, dass Marko genau das ist. Die Tatsache, dass Marko einen starken Hintergrund im Servicegesch\u00e4ft hat, ist eine gro\u00dfe Chance f\u00fcr uns, unsere eigenen Dienstleistungen voranzubringen. Auch aufgrund seiner Werte passt er gut in unseren Betrieb, was absolut wichtig f\u00fcr eine gute Zusammenarbeit ist.\u201c, sagt Petri M\u00e4kel\u00e4. &nbsp; Nachhaltigkeit und Service als Wettbewerbsvorteil Marko Orpana sieht das Gesch\u00e4ftsmodell von M\u00e4kel\u00e4 Alu, dem es gelungen ist, den Schwerpunkt vom selbst produzierten Produkt in ein Dienstleistungsgesch\u00e4ft umzuwandeln, als Differenzierungsfaktor und strategischen Wettbewerbsvorteil. Viele Aluminiumpresswerke produzieren nur Produkte. \u201eM\u00e4kel\u00e4 Alu erkennt, was der Kunde wirklich braucht, manchmal sogar besser als der Kunde selbst. Das ist es, worum es bei unserer Arbeit im Grunde geht. M\u00e4kel\u00e4 Alu m\u00f6chte wirklich Teil der Wertsch\u00f6pfungskette des Kunden sein und ihm helfen, sein eigenes Gesch\u00e4ft zu entwickeln\u201c, sagt er. M\u00e4kel\u00e4 Alu bietet seinen Kunden zum Beispiel einen Lagerservice und die Oberfl\u00e4chenbehandlung von Aluminiumprofilen, und diese Dienste k\u00f6nnen in die Kundenproduktion integriert werden. \u201eM\u00e4kel\u00e4 Alu ist ein Unternehmen, das sich nachhaltig weiterentwickeln will. Ob Wohlbefinden am Arbeitsplatz, Arbeitssicherheit oder Klimafragen: Nachhaltigkeit ist die treibende Kraft. Das Unternehmen \u00fcbernimmt Verantwortung f\u00fcr seine T\u00e4tigkeit und den Planeten, so gut es kann\u201c, sagt Marko Orpana. Mehr \u00fcber unsere Nachhaltigkeitsaktivit\u00e4ten unter \u201eNachhaltigkeit\u201c.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/\" \/>\n<meta property=\"og:site_name\" content=\"M&auml;kel&auml; Alu Oy\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-11T07:43:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-11T10:11:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/makelaalu.fi\/wp-content\/uploads\/2023\/01\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Susanna Korkiatupa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susanna Korkiatupa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/\"},\"author\":{\"name\":\"Susanna Korkiatupa\",\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#\\\/schema\\\/person\\\/9a809b6cc4e323d49d85ca0a349b40af\"},\"headline\":\"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana\",\"datePublished\":\"2023-01-11T07:43:47+00:00\",\"dateModified\":\"2023-01-11T10:11:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/\"},\"wordCount\":580,\"image\":{\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/makelaalu.fi\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg\",\"articleSection\":[\"Aktuelles\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/\",\"url\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/\",\"name\":\"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana - M&auml;kel&auml; Alu Oy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/makelaalu.fi\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg\",\"datePublished\":\"2023-01-11T07:43:47+00:00\",\"dateModified\":\"2023-01-11T10:11:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#\\\/schema\\\/person\\\/9a809b6cc4e323d49d85ca0a349b40af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/makelaalu.fi\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg\",\"contentUrl\":\"https:\\\/\\\/makelaalu.fi\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg\",\"width\":2000,\"height\":1334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/aktuelles\\\/unser-neuer-geschaftsfuhrer-marko-orpana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Frontpage\",\"item\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#website\",\"url\":\"https:\\\/\\\/dev.makelaalu.fi\\\/\",\"name\":\"M&auml;kel&auml; Alu Oy\",\"description\":\"Alumiiniprofiilien puristaminen vuosikymmenten kokemuksella.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev.makelaalu.fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dev.makelaalu.fi\\\/#\\\/schema\\\/person\\\/9a809b6cc4e323d49d85ca0a349b40af\",\"name\":\"Susanna Korkiatupa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g\",\"caption\":\"Susanna Korkiatupa\"},\"url\":\"https:\\\/\\\/makelaalu.fi\\\/de\\\/author\\\/susannak\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana - M&auml;kel&auml; Alu Oy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/","og_locale":"de_DE","og_type":"article","og_title":"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana - M&auml;kel&auml; Alu Oy","og_description":"Unser neuer Gesch\u00e4ftsf\u00fchrer hei\u00dft Marko Orpana. Der bisherige Gesch\u00e4ftsf\u00fchrer Petri M\u00e4kel\u00e4 bleibt weiterhin als Vorstandsvorsitzender in unserem Unternehmen t\u00e4tig. Herr Orpana arbeitet derzeit noch als Gesch\u00e4ftsf\u00fchrer des Softwareherstellers Rauhala Yhti\u00f6t Oy. Er verf\u00fcgt \u00fcber langj\u00e4hrige Erfahrung in der Leitung vom Servicegesch\u00e4ft. \u201eIch glaube, dass Marko uns in dieser Hinsicht viel zu bieten hat, aber vor allem glaube ich, dass er uns als kompetente F\u00fchrungskraft inspirieren wird. Ich freue mich sehr auf die Zusammenarbeit mit Marko\u201c, sagt Petri M\u00e4kel\u00e4. Marko Orpana startet am 1.3. in der Gesch\u00e4ftsf\u00fchrung von M\u00e4kel\u00e4 Alu. \u201eIch komme zu M\u00e4kel\u00e4 Alu mit gro\u00dfer Freude, aber auch mit Demut. M\u00e4kel\u00e4 Alu ist ein gro\u00dfer Player in der Branche, aber ich mag insbesondere die Unternehmenswerte und -strategie. Vor allem mit Petri haben wir sehr \u00e4hnliche Vorstellungen dar\u00fcber, wie die Dinge laufen sollen\u201c, sagt er. &nbsp; Langj\u00e4hrige Managementerfahrung In Kauhajoki geboren, lebt Marko Orpana mit seiner Familie nun in Sein\u00e4joki. Er hat einen Master-Abschluss in Wirtschaftswissenschaften. W\u00e4hrend seiner Zeit in S\u00fcdfinnland arbeitete er unter anderem f\u00fcr die Telekomkonzerne Elisa und Itella. Nachdem er nach S\u00fcd\u00f6sterbotten zur\u00fcckgekehrt war, arbeitete er lange Zeit f\u00fcr den Medienkonzern Ilkka-Yhtym\u00e4. \u201eMeine Aufgabe als F\u00fchrungskraft sehe ich so: ich bin im Kundenservice t\u00e4tig, und meine Kunden sind die Mitarbeiter des Unternehmens. Den Mitarbeitern ihre Arbeit in positiver Atmosph\u00e4re zu erm\u00f6glichen ist mir wichtig\u201c, sagt Orpana. \u201eIch gehe mit dem Gedanken an diese Aufgabe heran, dass ich in erster Linie lernen, zuh\u00f6ren und mit den Mitarbeitern austauschen werde. Ich freue mich schon darauf!\u201c, f\u00e4hrt er fort. Orpana wagt den Sprung in eine v\u00f6llig neue Branche. Das ist eine bewusste strategische Entscheidung von M\u00e4kel\u00e4 Alu. \u201eWir haben ein hochqualifiziertes Managementteam, das sich unserer Strategie verschrieben hat, und es ist gro\u00dfartig, dass wir unser Gesch\u00e4ft gemeinsam mit ihnen vorantreiben k\u00f6nnen. Deshalb haben wir nicht nach speziellen Fachkenntnissen in einem bestimmten Bereich gesucht, sondern nach einer guten F\u00fchrungspers\u00f6nlichkeit, und ich glaube, dass Marko genau das ist. Die Tatsache, dass Marko einen starken Hintergrund im Servicegesch\u00e4ft hat, ist eine gro\u00dfe Chance f\u00fcr uns, unsere eigenen Dienstleistungen voranzubringen. Auch aufgrund seiner Werte passt er gut in unseren Betrieb, was absolut wichtig f\u00fcr eine gute Zusammenarbeit ist.\u201c, sagt Petri M\u00e4kel\u00e4. &nbsp; Nachhaltigkeit und Service als Wettbewerbsvorteil Marko Orpana sieht das Gesch\u00e4ftsmodell von M\u00e4kel\u00e4 Alu, dem es gelungen ist, den Schwerpunkt vom selbst produzierten Produkt in ein Dienstleistungsgesch\u00e4ft umzuwandeln, als Differenzierungsfaktor und strategischen Wettbewerbsvorteil. Viele Aluminiumpresswerke produzieren nur Produkte. \u201eM\u00e4kel\u00e4 Alu erkennt, was der Kunde wirklich braucht, manchmal sogar besser als der Kunde selbst. Das ist es, worum es bei unserer Arbeit im Grunde geht. M\u00e4kel\u00e4 Alu m\u00f6chte wirklich Teil der Wertsch\u00f6pfungskette des Kunden sein und ihm helfen, sein eigenes Gesch\u00e4ft zu entwickeln\u201c, sagt er. M\u00e4kel\u00e4 Alu bietet seinen Kunden zum Beispiel einen Lagerservice und die Oberfl\u00e4chenbehandlung von Aluminiumprofilen, und diese Dienste k\u00f6nnen in die Kundenproduktion integriert werden. \u201eM\u00e4kel\u00e4 Alu ist ein Unternehmen, das sich nachhaltig weiterentwickeln will. Ob Wohlbefinden am Arbeitsplatz, Arbeitssicherheit oder Klimafragen: Nachhaltigkeit ist die treibende Kraft. Das Unternehmen \u00fcbernimmt Verantwortung f\u00fcr seine T\u00e4tigkeit und den Planeten, so gut es kann\u201c, sagt Marko Orpana. Mehr \u00fcber unsere Nachhaltigkeitsaktivit\u00e4ten unter \u201eNachhaltigkeit\u201c.","og_url":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/","og_site_name":"M&auml;kel&auml; Alu Oy","article_published_time":"2023-01-11T07:43:47+00:00","article_modified_time":"2023-01-11T10:11:51+00:00","og_image":[{"width":2000,"height":1334,"url":"https:\/\/makelaalu.fi\/wp-content\/uploads\/2023\/01\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg","type":"image\/jpeg"}],"author":"Susanna Korkiatupa","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Susanna Korkiatupa","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/#article","isPartOf":{"@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/"},"author":{"name":"Susanna Korkiatupa","@id":"https:\/\/dev.makelaalu.fi\/#\/schema\/person\/9a809b6cc4e323d49d85ca0a349b40af"},"headline":"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana","datePublished":"2023-01-11T07:43:47+00:00","dateModified":"2023-01-11T10:11:51+00:00","mainEntityOfPage":{"@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/"},"wordCount":580,"image":{"@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/#primaryimage"},"thumbnailUrl":"https:\/\/makelaalu.fi\/wp-content\/uploads\/2023\/01\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg","articleSection":["Aktuelles"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/","url":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/","name":"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana - M&auml;kel&auml; Alu Oy","isPartOf":{"@id":"https:\/\/dev.makelaalu.fi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/#primaryimage"},"image":{"@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/#primaryimage"},"thumbnailUrl":"https:\/\/makelaalu.fi\/wp-content\/uploads\/2023\/01\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg","datePublished":"2023-01-11T07:43:47+00:00","dateModified":"2023-01-11T10:11:51+00:00","author":{"@id":"https:\/\/dev.makelaalu.fi\/#\/schema\/person\/9a809b6cc4e323d49d85ca0a349b40af"},"breadcrumb":{"@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/#primaryimage","url":"https:\/\/makelaalu.fi\/wp-content\/uploads\/2023\/01\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg","contentUrl":"https:\/\/makelaalu.fi\/wp-content\/uploads\/2023\/01\/ma\u0308kela\u0308_alu_uusi_tj_marko_orpana.jpg","width":2000,"height":1334},{"@type":"BreadcrumbList","@id":"https:\/\/makelaalu.fi\/de\/aktuelles\/unser-neuer-geschaftsfuhrer-marko-orpana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Frontpage","item":"https:\/\/makelaalu.fi\/de\/"},{"@type":"ListItem","position":2,"name":"Unser neuer Gesch\u00e4ftsf\u00fchrer: Marko Orpana"}]},{"@type":"WebSite","@id":"https:\/\/dev.makelaalu.fi\/#website","url":"https:\/\/dev.makelaalu.fi\/","name":"M&auml;kel&auml; Alu Oy","description":"Alumiiniprofiilien puristaminen vuosikymmenten kokemuksella.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.makelaalu.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/dev.makelaalu.fi\/#\/schema\/person\/9a809b6cc4e323d49d85ca0a349b40af","name":"Susanna Korkiatupa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac071856daa4ddaa64ae267c8d2c7e83ab2b6d4c92c58fe68497193316213455?s=96&d=mm&r=g","caption":"Susanna Korkiatupa"},"url":"https:\/\/makelaalu.fi\/de\/author\/susannak\/"}]}},"_links":{"self":[{"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/posts\/9274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/comments?post=9274"}],"version-history":[{"count":3,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/posts\/9274\/revisions"}],"predecessor-version":[{"id":9281,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/posts\/9274\/revisions\/9281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/media\/9260"}],"wp:attachment":[{"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/media?parent=9274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/categories?post=9274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/makelaalu.fi\/de\/wp-json\/wp\/v2\/tags?post=9274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}